{"id":230702,"date":"2023-01-13T10:02:11","date_gmt":"2023-01-13T10:02:11","guid":{"rendered":"https:\/\/360businesstrips.com\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/"},"modified":"2023-11-21T20:55:51","modified_gmt":"2023-11-21T20:55:51","slug":"tour-gastronomico-por-el-barrio-de-jordaan","status":"publish","type":"project","link":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/","title":{"rendered":"Tour gastron\u00f3mico por el barrio de Jordaan"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#e0e0e0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb83.8%\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text content_tablet=\u00bb<\/p>\n<h6><a href=%22https:\/\/360businesstrips.com\/es\/actividades-y-experiencias\/%22>< Volver a todas las experiencias<\/a><\/h6>\n<h1>Tour gastron\u00f3mico del distrito Jordaan<\/h1>\n<h4>Siga los pasos de la comida por el barrio Jordaan de \u00c1msterdam en una experiencia culinaria<\/h4>\n<p>\u00bb content_phone=\u00bb<\/p>\n<h6><a href=%22https:\/\/360businesstrips.com\/es\/actividades-y-experiencias\/%22>< Volver a todas las experiencias<\/a><\/h6>\n<h1>Tour gastron\u00f3mico del distrito Jordaan<\/h1>\n<h4>Siga los pasos de la comida por el barrio Jordaan de \u00c1msterdam en una experiencia culinaria<\/h4>\n<p>\u00bb content_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb72px\u00bb header_4_font_size=\u00bb22px\u00bb header_4_line_height=\u00bb1.3em\u00bb header_6_font=\u00bbLato|||on|||||\u00bb header_6_text_color=\u00bb#ff6600&#8243; header_6_letter_spacing=\u00bb2px\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_font_size_tablet=\u00bb72px\u00bb header_font_size_phone=\u00bb50px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h6><a href=\"https:\/\/360businesstrips.com\/es\/actividades-y-experiencias\/\">&lt; Volver a todas las experiencias<\/a><\/h6>\n<h1>Tour gastron\u00f3mico del distrito Jordaan<\/h1>\n<h4>Siga los pasos de la comida por el barrio Jordaan de \u00c1msterdam en una experiencia culinaria<\/h4>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/#contact\u00bb button_text=\u00bbSolicitar cotizaci\u00f3n\u00bb button_alignment=\u00bbleft\u00bb button_alignment_tablet=\u00bbright\u00bb button_alignment_phone=\u00bbleft\u00bb button_alignment_last_edited=\u00bbon|phone\u00bb disabled_on=\u00bboff|off|off\u00bb module_id=\u00bboverlay_unique_id_81&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#ff6600&#8243; button_border_width=\u00bb2px\u00bb button_border_radius=\u00bb25px\u00bb button_font=\u00bbLato|700|||||||\u00bb button_use_icon=\u00bboff\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/360businesstrips.com\/wp-content\/uploads\/2022\/10\/Food-tour-desktop.jpg\u00bb title_text=\u00bbS\u00e1ndwich casero vegano de Jackfruit a la barbacoa\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#e0e0e0&#8243; custom_padding=\u00bb5px||0px||false|false\u00bb custom_padding_tablet=\u00bb5px||0px||false|false\u00bb custom_padding_phone=\u00bb||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb2px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bbon|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb20px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bbLato||||||||\u00bb header_font_size=\u00bb35px\u00bb width=\u00bb70%\u00bb max_width=\u00bb100%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|true\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Descripci\u00f3n<\/h1>\n<p><span>Una forma estupenda de trabajar en equipo. Ad\u00e9ntrese en los fogones del barrio de Jordaan con esta emocionante y sabrosa b\u00fasqueda del tesoro. Encontrar\u00e1s los mejores sitios para comer y probar algo especial en cada lugar.<\/span><br \/><span>Ofrecemos una gran variedad de deliciosos tentempi\u00e9s, y en cada lugar te dan una pista para encontrar el siguiente. As\u00ed conocer\u00e1 el barrio de forma l\u00fadica pero con buen gusto.<\/span><\/p>\n<p><span>Las opciones vegetarianas tambi\u00e9n se tienen en cuenta en casi todos los lugares.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|on|on\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb text_font_size_tablet=\u00bb18px\u00bb text_font_size_phone=\u00bb20px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_4_font_size_tablet=\u00bb\u00bb header_4_font_size_phone=\u00bb20px\u00bb header_4_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: left;\">Descripci\u00f3n<\/h1>\n<h4 style=\"text-align: left;\"><span>Una forma estupenda de trabajar en equipo. <\/span>Ad\u00e9ntrese en el barrio de Jordaan con esta emocionante b\u00fasqueda del tesoro. Encontrar\u00e1s los mejores sitios para comer y probar algo especial en cada lugar.<br \/>Ofrecemos una gran variedad de deliciosos tentempi\u00e9s, y en cada lugar te dan una pista para encontrar el siguiente. As\u00ed conocer\u00e1 el barrio de forma l\u00fadica pero con buen gusto.<\/h4>\n<p>Las opciones vegetarianas tambi\u00e9n se tienen en cuenta en casi todos los lugares.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bbon|off|off\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbLato||||||||\u00bb header_font_size=\u00bb40px\u00bb header_2_font=\u00bbLato||||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb35px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Informaci\u00f3n adicional<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-25px|auto||auto|false|false\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bbon|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb31px\u00bb width=\u00bb70%\u00bb max_width=\u00bb100%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|||-41px||\u00bb custom_css_main_element=\u00bb||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<table style=\"width: 110.915%; border-collapse: collapse; border-style: hidden;\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 219.531px; border-style: hidden; vertical-align: middle; text-align: right;\" scope=\"rowgroup\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18630 alignnone size-full\" src=\"https:\/\/360businesstrips.com\/wp-content\/uploads\/2022\/10\/Dutch-house-2.png\" alt=\"\" width=\"165\" height=\"151\" \/><\/td>\n<td style=\"width: 618.344px;\">\n<p style=\"padding-left: 0px;\"><strong>Detalles de la actividad<br \/><\/strong><span style=\"color: #ff6600;\">\u2022<\/span> 5 <span>lugares de comida en la zona de Jordaan de \u00c1msterdam.<\/span><br \/><span style=\"color: #ff6600;\">\u2022<\/span> <span>Dutch and international snacks.<br \/><span style=\"color: #ff6600;\">\u2022<\/span> You may choose to have a drink or a snack at each stop.<\/span><br \/><span style=\"color: #ff6600;\">\u2022<\/span> <span>Las indicaciones para llegar al siguiente punto le esperan en cada lugar.<\/span><br \/><span style=\"color: #ff6600;\">\u2022<\/span> Esta actividad tambi\u00e9n est\u00e1 disponible en espa\u00f1ol, neerland\u00e9s, alem\u00e1n, franc\u00e9s, italiano y portugu\u00e9s.<br \/><span style=\"color: #ff6600;\">\u2022<\/span> <span>Soporte de asistencia remota v\u00eda WhatsApp con uno de nuestros empleados de 360 Business Trips (en caso de p\u00e1nico).<\/span><\/p>\n<p style=\"padding-left: 0px;\"><strong>Opcional:<\/strong><br \/><span style=\"color: #ff6600;\">\u2022<\/span> Reservar una sala de reuniones junto a esta actividad en la zona cercana.<br \/><span style=\"color: #ff6600;\">\u2022<\/span> Transporte.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"padding-left: 20px;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-25px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bboff|on|on\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_font_size=\u00bb20px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bbLato||||||||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Informaci\u00f3n adicional<\/h1>\n<p style=\"padding-left: 0px;\"><strong>Detalles de la actividad<br \/><\/strong><span style=\"color: #ff6600;\">\u2022<\/span> 5 <span>lugares de comida en la zona de Jordaan de \u00c1msterdam.<\/span><br \/><span style=\"color: #ff6600;\">\u2022<\/span> <span>Dutch and international snacks.<br \/><span style=\"color: #ff6600;\">\u2022<\/span> You may choose to have a drink or a snack at each stop.<\/span><br \/><span style=\"color: #ff6600;\">\u2022<\/span> <span>Las indicaciones para llegar al siguiente punto le esperan en cada lugar.<\/span><br \/><span style=\"color: #ff6600;\">\u2022<\/span> Esta actividad tambi\u00e9n est\u00e1 disponible en espa\u00f1ol, neerland\u00e9s, alem\u00e1n, franc\u00e9s, italiano y portugu\u00e9s.<br \/><span style=\"color: #ff6600;\">\u2022<\/span> <span>Soporte de asistencia remota v\u00eda WhatsApp con uno de nuestros empleados de 360 Business Trips (en caso de p\u00e1nico).<\/span><\/p>\n<p style=\"padding-left: 0px;\"><strong>Opcional:<\/strong><br \/><span style=\"color: #ff6600;\">\u2022<\/span> Reservar una sala de reuniones junto a esta actividad en la zona cercana.<br \/><span style=\"color: #ff6600;\">\u2022<\/span> Transporte.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbcontact\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbRoboto|500|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_margin_tablet=\u00bb||31px|||\u00bb custom_margin_phone=\u00bb-50px||31px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb\u00bb header_2_font_size_phone=\u00bb26px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h2>\u00bfEstas interesado en m\u00e1s informaci\u00f3n?<\/h2>\n<h2>Solicite una cotizaci\u00f3n<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][wpforms_selector form_id=\u00bb232617&#8243; show_title=\u00bboff\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb|||100px|false|false\u00bb custom_margin_tablet=\u00bb|||100px|false|false\u00bb custom_margin_phone=\u00bb-60px|||0px|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; module_alignment_tablet=\u00bb\u00bb module_alignment_phone=\u00bb\u00bb module_alignment_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/wpforms_selector][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt; Volver a todas las experiencias Tour gastron\u00f3mico del distrito Jordaan Siga los pasos de la comida por el barrio Jordaan de \u00c1msterdam en una experiencia culinariaDescripci\u00f3n Una forma estupenda de trabajar en equipo. Ad\u00e9ntrese en los fogones del barrio de Jordaan con esta emocionante y sabrosa b\u00fasqueda del tesoro. Encontrar\u00e1s los mejores sitios para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":234478,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"project_category":[108,72,111,80,119],"project_tag":[],"class_list":["post-230702","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-creacion-de-equipos","project_category-games","project_category-juegos","project_category-team-building","project_category-visitas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tour gastron\u00f3mico por el barrio de Jordaan - Corporate Events and Team Building Activities Amsterdam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour gastron\u00f3mico por el barrio de Jordaan\" \/>\n<meta property=\"og:description\" content=\"&lt; Volver a todas las experiencias Tour gastron\u00f3mico del distrito Jordaan Siga los pasos de la comida por el barrio Jordaan de \u00c1msterdam en una experiencia culinariaDescripci\u00f3n Una forma estupenda de trabajar en equipo. Ad\u00e9ntrese en los fogones del barrio de Jordaan con esta emocionante y sabrosa b\u00fasqueda del tesoro. Encontrar\u00e1s los mejores sitios para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/\" \/>\n<meta property=\"og:site_name\" content=\"Corporate Events and Team Building Activities Amsterdam\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T20:55:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/360businesstrips.com\/wp-content\/uploads\/2022\/10\/Food-tour-desktop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/\",\"url\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/\",\"name\":\"Tour gastron\u00f3mico por el barrio de Jordaan - Corporate Events and Team Building Activities Amsterdam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/360businesstrips.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Food-tour-de-pijp-amsterdam-800x530-1.jpg\",\"datePublished\":\"2023-01-13T10:02:11+00:00\",\"dateModified\":\"2023-11-21T20:55:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/360businesstrips.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Food-tour-de-pijp-amsterdam-800x530-1.jpg\",\"contentUrl\":\"https:\\\/\\\/360businesstrips.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Food-tour-de-pijp-amsterdam-800x530-1.jpg\",\"width\":800,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/tour-gastronomico-por-el-barrio-de-jordaan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tour gastron\u00f3mico por el barrio de Jordaan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/\",\"name\":\"360 Business Trips\",\"description\":\"Business Travel, Team Building Activities &amp; Events\",\"publisher\":{\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/#organization\",\"name\":\"360 Business Trips\",\"url\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/360businesstrips.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/360-logo-round_orange@2x-Mobile-1.png\",\"contentUrl\":\"https:\\\/\\\/360businesstrips.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/360-logo-round_orange@2x-Mobile-1.png\",\"width\":501,\"height\":501,\"caption\":\"360 Business Trips\"},\"image\":{\"@id\":\"https:\\\/\\\/360businesstrips.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour gastron\u00f3mico por el barrio de Jordaan - Corporate Events and Team Building Activities Amsterdam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/","og_locale":"es_ES","og_type":"article","og_title":"Tour gastron\u00f3mico por el barrio de Jordaan","og_description":"&lt; Volver a todas las experiencias Tour gastron\u00f3mico del distrito Jordaan Siga los pasos de la comida por el barrio Jordaan de \u00c1msterdam en una experiencia culinariaDescripci\u00f3n Una forma estupenda de trabajar en equipo. Ad\u00e9ntrese en los fogones del barrio de Jordaan con esta emocionante y sabrosa b\u00fasqueda del tesoro. Encontrar\u00e1s los mejores sitios para [&hellip;]","og_url":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/","og_site_name":"Corporate Events and Team Building Activities Amsterdam","article_modified_time":"2023-11-21T20:55:51+00:00","og_image":[{"width":800,"height":530,"url":"https:\/\/360businesstrips.com\/wp-content\/uploads\/2022\/10\/Food-tour-desktop.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/","url":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/","name":"Tour gastron\u00f3mico por el barrio de Jordaan - Corporate Events and Team Building Activities Amsterdam","isPartOf":{"@id":"https:\/\/360businesstrips.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/#primaryimage"},"image":{"@id":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/#primaryimage"},"thumbnailUrl":"https:\/\/360businesstrips.com\/wp-content\/uploads\/2025\/08\/Food-tour-de-pijp-amsterdam-800x530-1.jpg","datePublished":"2023-01-13T10:02:11+00:00","dateModified":"2023-11-21T20:55:51+00:00","breadcrumb":{"@id":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/#primaryimage","url":"https:\/\/360businesstrips.com\/wp-content\/uploads\/2025\/08\/Food-tour-de-pijp-amsterdam-800x530-1.jpg","contentUrl":"https:\/\/360businesstrips.com\/wp-content\/uploads\/2025\/08\/Food-tour-de-pijp-amsterdam-800x530-1.jpg","width":800,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/360businesstrips.com\/es\/project\/tour-gastronomico-por-el-barrio-de-jordaan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/360businesstrips.com\/es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/360businesstrips.com\/es\/project\/"},{"@type":"ListItem","position":3,"name":"Tour gastron\u00f3mico por el barrio de Jordaan"}]},{"@type":"WebSite","@id":"https:\/\/360businesstrips.com\/es\/#website","url":"https:\/\/360businesstrips.com\/es\/","name":"360 Business Trips","description":"Business Travel, Team Building Activities &amp; Events","publisher":{"@id":"https:\/\/360businesstrips.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/360businesstrips.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/360businesstrips.com\/es\/#organization","name":"360 Business Trips","url":"https:\/\/360businesstrips.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/360businesstrips.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/360businesstrips.com\/wp-content\/uploads\/2023\/10\/360-logo-round_orange@2x-Mobile-1.png","contentUrl":"https:\/\/360businesstrips.com\/wp-content\/uploads\/2023\/10\/360-logo-round_orange@2x-Mobile-1.png","width":501,"height":501,"caption":"360 Business Trips"},"image":{"@id":"https:\/\/360businesstrips.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/project\/230702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/comments?post=230702"}],"version-history":[{"count":5,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/project\/230702\/revisions"}],"predecessor-version":[{"id":233099,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/project\/230702\/revisions\/233099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/media\/234478"}],"wp:attachment":[{"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/media?parent=230702"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/project_category?post=230702"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/360businesstrips.com\/es\/wp-json\/wp\/v2\/project_tag?post=230702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}